{"id":6965,"date":"2023-04-12T08:14:16","date_gmt":"2023-04-12T06:14:16","guid":{"rendered":"https:\/\/bersub.com\/produit\/bersub-explo-6-evo-aa\/"},"modified":"2025-12-06T18:02:52","modified_gmt":"2025-12-06T17:02:52","slug":"bersub-explo-6-evo-aa","status":"publish","type":"product","link":"https:\/\/bersub.com\/nl\/produit\/bersub-explo-6-evo-aa\/","title":{"rendered":"BERSUB - Explo 6 EVO AA"},"content":{"rendered":"<p>Le phare de plong\u00e9e BERSUB Explo 6 EVO AA est con\u00e7u pour l&rsquo;exploration sous-marine dans toutes les conditions de plong\u00e9e.<br \/>\nIl conviendra parfaitement \u00e0 des plongeurs occasionnels. Vous pouvez l\u2019emmener dans toutes les eaux, sa puissance sera largement suffisante pour toutes vos plong\u00e9es.<\/p>\n<p>Les mod\u00e8les EVO AA b\u00e9n\u00e9ficient de nouvelles LED apportant 10% de puissance suppl\u00e9mentaire.<\/p>\n<p>Cette version dispose d\u2019une temp\u00e9rature de couleur de 6000K blanc pur (pas d\u2019effet bleut\u00e9). Elle sera parfaite pour les plong\u00e9es en eaux charg\u00e9es comme en eau claire.<\/p>\n<p>Elle dispose d\u2019un interrupteur m\u00e9canique facilement manipulable (m\u00eame avec un gant) par simple rotation qui vous permet de r\u00e9gler l\u2019intensit\u00e9 lumineuse sur 3 niveaux pour g\u00e9rer votre autonomie et la puissance comme vous le souhaitez.<\/p>\n<p>Le mod\u00e8le EVO AA fonctionne avec des piles standards ou rechargeables au format AA que l\u2019on trouve tr\u00e8s facilement dans le monde entier. Il ne n\u00e9cessite aucun entretien si ce n\u2019est d\u2019enlever les piles en p\u00e9riode de non utilisation<\/p>\n<p>Tous les phares Bersub peuvent \u00eatre utilis\u00e9s en syst\u00e8me d\u00e9port\u00e9 avec un Connect-System<\/p>\n<p>Une s\u00e9curit\u00e9 m\u00e9canique emp\u00eache tout allumage intempestif.<\/p>\n<p>Con\u00e7u pour \u00eatre tr\u00e8s r\u00e9sistant, il est fabriqu\u00e9 avec un corps en Delrin tr\u00e8s robuste et une t\u00eate aluminium anodis\u00e9 de qualit\u00e9 marine dure d\u2019une \u00e9paisseur de 4 mm sur sa partie la plus fine.<\/p>\n<p>L\u2019\u00e9tanch\u00e9it\u00e9 de tous les phares de plong\u00e9e BERSUB est garantie par des doubles joints toriques avec un traitement Teflon qui ne n\u00e9cessitent pas de graissage. Cela \u00e9vite que des impuret\u00e9s se collent aux joints et provoquent d\u2019\u00e9ventuelles prises d\u2019eau.<br \/>\nIl peut \u00eatre utilis\u00e9 hors de l\u2019eau sans restriction.<br \/>\nTous les phares de plong\u00e9e sous-marine BERSUB sont \u00e9tanches jusqu&rsquo; \u00e0 300m.<\/p>","protected":false},"excerpt":{"rendered":"<p>De Explo 6 EVO AA is de duiklamp voor verkenning in alle soorten water. Met zijn 15\u00b0 stralingshoek en hoge vermogen is hij net zo effectief in de zee als in het meer.<br \/>\nWerkt op standaard of oplaadbare AA-batterijen<\/p>","protected":false},"featured_media":5834,"template":"","meta":[],"product_brand":[],"product_cat":[151,152],"product_tag":[],"class_list":["post-6965","product","type-product","status-publish","has-post-thumbnail","product_cat-eclairages-de-plongee","product_cat-eclairages-de-plongee-exploration","brand-bersub","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BERSUB - Explo 6 EVO AA - Bersub<\/title>\n<meta name=\"description\" content=\"Le phare de plong\u00e9e BERSUB Explo 6 EVO AA est con\u00e7u pour l&#039;exploration sous-marine dans toutes les conditions de plong\u00e9e pour des plongeurs occasionnels\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bersub.com\/nl\/product-2\/bersub-explo-6-evo-aa\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BERSUB - Explo 6 EVO AA - Bersub\" \/>\n<meta property=\"og:description\" content=\"Le phare de plong\u00e9e BERSUB Explo 6 EVO AA est con\u00e7u pour l&#039;exploration sous-marine dans toutes les conditions de plong\u00e9e pour des plongeurs occasionnels\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bersub.com\/nl\/product-2\/bersub-explo-6-evo-aa\/\" \/>\n<meta property=\"og:site_name\" content=\"Bersub\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-06T17:02:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bersub.com\/wp-content\/uploads\/2023\/04\/bersub-lampe-de-plongee-explo-6-evo-aa-bleu-55lev32y0600a4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bersub.com\\\/produit\\\/bersub-explo-6-evo-aa\\\/\",\"url\":\"https:\\\/\\\/bersub.com\\\/produit\\\/bersub-explo-6-evo-aa\\\/\",\"name\":\"BERSUB - Explo 6 EVO AA - Bersub\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bersub.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bersub.com\\\/produit\\\/bersub-explo-6-evo-aa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bersub.com\\\/produit\\\/bersub-explo-6-evo-aa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bersub.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/bersub-lampe-de-plongee-explo-6-evo-aa-bleu-55lev32y0600a4.jpg\",\"datePublished\":\"2023-04-12T06:14:16+00:00\",\"dateModified\":\"2025-12-06T17:02:52+00:00\",\"description\":\"Le phare de plong\u00e9e BERSUB Explo 6 EVO AA est con\u00e7u pour l'exploration sous-marine dans toutes les conditions de plong\u00e9e pour des plongeurs occasionnels\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bersub.com\\\/produit\\\/bersub-explo-6-evo-aa\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bersub.com\\\/produit\\\/bersub-explo-6-evo-aa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/bersub.com\\\/produit\\\/bersub-explo-6-evo-aa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bersub.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/bersub-lampe-de-plongee-explo-6-evo-aa-bleu-55lev32y0600a4.jpg\",\"contentUrl\":\"https:\\\/\\\/bersub.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/bersub-lampe-de-plongee-explo-6-evo-aa-bleu-55lev32y0600a4.jpg\",\"width\":1280,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bersub.com\\\/produit\\\/bersub-explo-6-evo-aa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bersub.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/bersub.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BERSUB &#8211; Explo 6 EVO AA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bersub.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/bersub.com\\\/en\\\/\",\"name\":\"Bersub\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/bersub.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bersub.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bersub.com\\\/en\\\/#organization\",\"name\":\"Bersub\",\"url\":\"https:\\\/\\\/bersub.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/bersub.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bersub.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-bersub-blanc.png\",\"contentUrl\":\"https:\\\/\\\/bersub.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-bersub-blanc.png\",\"width\":400,\"height\":144,\"caption\":\"Bersub\"},\"image\":{\"@id\":\"https:\\\/\\\/bersub.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BERSUB - Explo 6 EVO AA - Bersub","description":"De BERSUB Explo 6 EVO AA duiklamp is ontworpen voor onderwaterverkenning in alle duikomstandigheden voor gelegenheidsduikers.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bersub.com\/nl\/product-2\/bersub-explo-6-evo-aa\/","og_locale":"nl_NL","og_type":"article","og_title":"BERSUB - Explo 6 EVO AA - Bersub","og_description":"Le phare de plong\u00e9e BERSUB Explo 6 EVO AA est con\u00e7u pour l'exploration sous-marine dans toutes les conditions de plong\u00e9e pour des plongeurs occasionnels","og_url":"https:\/\/bersub.com\/nl\/product-2\/bersub-explo-6-evo-aa\/","og_site_name":"Bersub","article_modified_time":"2025-12-06T17:02:52+00:00","og_image":[{"width":1280,"height":1280,"url":"https:\/\/bersub.com\/wp-content\/uploads\/2023\/04\/bersub-lampe-de-plongee-explo-6-evo-aa-bleu-55lev32y0600a4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bersub.com\/produit\/bersub-explo-6-evo-aa\/","url":"https:\/\/bersub.com\/produit\/bersub-explo-6-evo-aa\/","name":"BERSUB - Explo 6 EVO AA - Bersub","isPartOf":{"@id":"https:\/\/bersub.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bersub.com\/produit\/bersub-explo-6-evo-aa\/#primaryimage"},"image":{"@id":"https:\/\/bersub.com\/produit\/bersub-explo-6-evo-aa\/#primaryimage"},"thumbnailUrl":"https:\/\/bersub.com\/wp-content\/uploads\/2023\/04\/bersub-lampe-de-plongee-explo-6-evo-aa-bleu-55lev32y0600a4.jpg","datePublished":"2023-04-12T06:14:16+00:00","dateModified":"2025-12-06T17:02:52+00:00","description":"De BERSUB Explo 6 EVO AA duiklamp is ontworpen voor onderwaterverkenning in alle duikomstandigheden voor gelegenheidsduikers.","breadcrumb":{"@id":"https:\/\/bersub.com\/produit\/bersub-explo-6-evo-aa\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bersub.com\/produit\/bersub-explo-6-evo-aa\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/bersub.com\/produit\/bersub-explo-6-evo-aa\/#primaryimage","url":"https:\/\/bersub.com\/wp-content\/uploads\/2023\/04\/bersub-lampe-de-plongee-explo-6-evo-aa-bleu-55lev32y0600a4.jpg","contentUrl":"https:\/\/bersub.com\/wp-content\/uploads\/2023\/04\/bersub-lampe-de-plongee-explo-6-evo-aa-bleu-55lev32y0600a4.jpg","width":1280,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/bersub.com\/produit\/bersub-explo-6-evo-aa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bersub.com\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/bersub.com\/shop\/"},{"@type":"ListItem","position":3,"name":"BERSUB &#8211; Explo 6 EVO AA"}]},{"@type":"WebSite","@id":"https:\/\/bersub.com\/en\/#website","url":"https:\/\/bersub.com\/en\/","name":"Bersub","description":"","publisher":{"@id":"https:\/\/bersub.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bersub.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/bersub.com\/en\/#organization","name":"Bersub","url":"https:\/\/bersub.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/bersub.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/bersub.com\/wp-content\/uploads\/2021\/01\/logo-bersub-blanc.png","contentUrl":"https:\/\/bersub.com\/wp-content\/uploads\/2021\/01\/logo-bersub-blanc.png","width":400,"height":144,"caption":"Bersub"},"image":{"@id":"https:\/\/bersub.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/bersub.com\/nl\/wp-json\/wp\/v2\/product\/6965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bersub.com\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bersub.com\/nl\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/bersub.com\/nl\/wp-json\/wp\/v2\/product\/6965\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bersub.com\/nl\/wp-json\/wp\/v2\/media\/5834"}],"wp:attachment":[{"href":"https:\/\/bersub.com\/nl\/wp-json\/wp\/v2\/media?parent=6965"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bersub.com\/nl\/wp-json\/wp\/v2\/product_brand?post=6965"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bersub.com\/nl\/wp-json\/wp\/v2\/product_cat?post=6965"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bersub.com\/nl\/wp-json\/wp\/v2\/product_tag?post=6965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}