{"id":9698,"date":"2023-12-01T22:19:36","date_gmt":"2023-12-01T21:19:36","guid":{"rendered":"https:\/\/bersub.com\/?post_type=product&#038;p=9698"},"modified":"2026-07-01T16:13:52","modified_gmt":"2026-07-01T14:13:52","slug":"dragon-de-bersub-en-espiral-armado-con-mosqueton-y-anillas-de-kevlar","status":"publish","type":"product","link":"https:\/\/bersub.com\/es\/produit\/bersub-dragonne-spirale-armee-avec-mousqueton-et-anneaux-kevlar\/","title":{"rendered":"BERSUB - Eslinga en espiral reforzada con Kevlar y mosquet\u00f3n de acero inoxidable"},"content":{"rendered":"<p>Dragonne spirale arm\u00e9e BERSUB.<br \/>\nLe permite fijar sus accesorios (faros, luces, br\u00fajulas, etc.) en la pica para que no se pierdan si los maneja de forma incorrecta.<\/p>\n<p>Spirale arm\u00e9e d\u2019un c\u00e2ble Kevlar pour une s\u00e9curit\u00e9 maximale.<br \/>\nAnillas y mosquet\u00f3n de acero inoxidable.<br \/>\nPeso: 90 g<br \/>\nM\u00e1s fino y ligero que los modelos convencionales.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Eslinga espiral Bersub armada con cable Kevlar y mosquet\u00f3n de acero inoxidable<\/p>\n<p>Para sujetar la linterna de buceo u otro equipo.<\/p>\n<p>M\u00e1s fino y ligero que los modelos convencionales.<\/p>\n<p>Diferentes colores para elegir<\/p>","protected":false},"featured_media":5590,"template":"","meta":[],"product_brand":[],"product_cat":[134,138],"product_tag":[],"class_list":["post-9698","product","type-product","status-publish","has-post-thumbnail","product_cat-accessoires","product_cat-accessoires-protection-et-securite","brand-bersub","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BERSUB - Dragonne spirale arm\u00e9e Kevlar avec mousqueton inox - Bersub<\/title>\n<meta name=\"description\" content=\"Dragonne spirale arm\u00e9 BERSUB. Elle permet de s\u00e9curiser ses accessoires (phares, lampes, torches, compas\u2026)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bersub.com\/es\/producto-3\/dragon-de-bersub-en-espiral-armado-con-mosqueton-y-anillas-de-kevlar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BERSUB - Dragonne spirale arm\u00e9e Kevlar avec mousqueton inox - Bersub\" \/>\n<meta property=\"og:description\" content=\"Dragonne spirale arm\u00e9 BERSUB. Elle permet de s\u00e9curiser ses accessoires (phares, lampes, torches, compas\u2026)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bersub.com\/es\/producto-3\/dragon-de-bersub-en-espiral-armado-con-mosqueton-y-anillas-de-kevlar\/\" \/>\n<meta property=\"og:site_name\" content=\"Bersub\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-01T14:13:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bersub.com\/wp-content\/uploads\/2023\/04\/bersub-lampe-de-plongee-accessoires-dragonne-spirale-kevlar-orange-1906062.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bersub.com\\\/produit\\\/bersub-dragonne-spirale-armee-avec-mousqueton-et-anneaux-kevlar\\\/\",\"url\":\"https:\\\/\\\/bersub.com\\\/produit\\\/bersub-dragonne-spirale-armee-avec-mousqueton-et-anneaux-kevlar\\\/\",\"name\":\"BERSUB - Dragonne spirale arm\u00e9e Kevlar avec mousqueton inox - Bersub\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bersub.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bersub.com\\\/produit\\\/bersub-dragonne-spirale-armee-avec-mousqueton-et-anneaux-kevlar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bersub.com\\\/produit\\\/bersub-dragonne-spirale-armee-avec-mousqueton-et-anneaux-kevlar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bersub.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/bersub-lampe-de-plongee-accessoires-dragonne-spirale-kevlar-orange-1906062.jpg\",\"datePublished\":\"2023-12-01T21:19:36+00:00\",\"dateModified\":\"2026-07-01T14:13:52+00:00\",\"description\":\"Dragonne spirale arm\u00e9 BERSUB. Elle permet de s\u00e9curiser ses accessoires (phares, lampes, torches, compas\u2026)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bersub.com\\\/produit\\\/bersub-dragonne-spirale-armee-avec-mousqueton-et-anneaux-kevlar\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bersub.com\\\/produit\\\/bersub-dragonne-spirale-armee-avec-mousqueton-et-anneaux-kevlar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/bersub.com\\\/produit\\\/bersub-dragonne-spirale-armee-avec-mousqueton-et-anneaux-kevlar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bersub.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/bersub-lampe-de-plongee-accessoires-dragonne-spirale-kevlar-orange-1906062.jpg\",\"contentUrl\":\"https:\\\/\\\/bersub.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/bersub-lampe-de-plongee-accessoires-dragonne-spirale-kevlar-orange-1906062.jpg\",\"width\":1280,\"height\":1280,\"caption\":\"Dragonne spirale arm\u00e9e Kevlar pour phare de plong\u00e9e BERSUB orange\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bersub.com\\\/produit\\\/bersub-dragonne-spirale-armee-avec-mousqueton-et-anneaux-kevlar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bersub.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/bersub.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BERSUB &#8211; Dragonne spirale arm\u00e9e Kevlar avec mousqueton inox\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bersub.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/bersub.com\\\/en\\\/\",\"name\":\"Bersub\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/bersub.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bersub.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bersub.com\\\/en\\\/#organization\",\"name\":\"Bersub\",\"url\":\"https:\\\/\\\/bersub.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/bersub.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bersub.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-bersub-blanc.png\",\"contentUrl\":\"https:\\\/\\\/bersub.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-bersub-blanc.png\",\"width\":400,\"height\":144,\"caption\":\"Bersub\"},\"image\":{\"@id\":\"https:\\\/\\\/bersub.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BERSUB - Eslinga en espiral reforzada con Kevlar y mosquet\u00f3n de acero inoxidable - Bersub","description":"Correa espiral armada BERSUB. Para asegurar accesorios (faros, l\u00e1mparas, linternas, br\u00fajulas, etc.).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bersub.com\/es\/producto-3\/dragon-de-bersub-en-espiral-armado-con-mosqueton-y-anillas-de-kevlar\/","og_locale":"es_ES","og_type":"article","og_title":"BERSUB - Dragonne spirale arm\u00e9e Kevlar avec mousqueton inox - Bersub","og_description":"Dragonne spirale arm\u00e9 BERSUB. Elle permet de s\u00e9curiser ses accessoires (phares, lampes, torches, compas\u2026)","og_url":"https:\/\/bersub.com\/es\/producto-3\/dragon-de-bersub-en-espiral-armado-con-mosqueton-y-anillas-de-kevlar\/","og_site_name":"Bersub","article_modified_time":"2026-07-01T14:13:52+00:00","og_image":[{"width":1280,"height":1280,"url":"https:\/\/bersub.com\/wp-content\/uploads\/2023\/04\/bersub-lampe-de-plongee-accessoires-dragonne-spirale-kevlar-orange-1906062.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bersub.com\/produit\/bersub-dragonne-spirale-armee-avec-mousqueton-et-anneaux-kevlar\/","url":"https:\/\/bersub.com\/produit\/bersub-dragonne-spirale-armee-avec-mousqueton-et-anneaux-kevlar\/","name":"BERSUB - Eslinga en espiral reforzada con Kevlar y mosquet\u00f3n de acero inoxidable - Bersub","isPartOf":{"@id":"https:\/\/bersub.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bersub.com\/produit\/bersub-dragonne-spirale-armee-avec-mousqueton-et-anneaux-kevlar\/#primaryimage"},"image":{"@id":"https:\/\/bersub.com\/produit\/bersub-dragonne-spirale-armee-avec-mousqueton-et-anneaux-kevlar\/#primaryimage"},"thumbnailUrl":"https:\/\/bersub.com\/wp-content\/uploads\/2023\/04\/bersub-lampe-de-plongee-accessoires-dragonne-spirale-kevlar-orange-1906062.jpg","datePublished":"2023-12-01T21:19:36+00:00","dateModified":"2026-07-01T14:13:52+00:00","description":"Correa espiral armada BERSUB. Para asegurar accesorios (faros, l\u00e1mparas, linternas, br\u00fajulas, etc.).","breadcrumb":{"@id":"https:\/\/bersub.com\/produit\/bersub-dragonne-spirale-armee-avec-mousqueton-et-anneaux-kevlar\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bersub.com\/produit\/bersub-dragonne-spirale-armee-avec-mousqueton-et-anneaux-kevlar\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/bersub.com\/produit\/bersub-dragonne-spirale-armee-avec-mousqueton-et-anneaux-kevlar\/#primaryimage","url":"https:\/\/bersub.com\/wp-content\/uploads\/2023\/04\/bersub-lampe-de-plongee-accessoires-dragonne-spirale-kevlar-orange-1906062.jpg","contentUrl":"https:\/\/bersub.com\/wp-content\/uploads\/2023\/04\/bersub-lampe-de-plongee-accessoires-dragonne-spirale-kevlar-orange-1906062.jpg","width":1280,"height":1280,"caption":"Dragonne spirale arm\u00e9e Kevlar pour phare de plong\u00e9e BERSUB orange"},{"@type":"BreadcrumbList","@id":"https:\/\/bersub.com\/produit\/bersub-dragonne-spirale-armee-avec-mousqueton-et-anneaux-kevlar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bersub.com\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/bersub.com\/shop\/"},{"@type":"ListItem","position":3,"name":"BERSUB &#8211; Dragonne spirale arm\u00e9e Kevlar avec mousqueton inox"}]},{"@type":"WebSite","@id":"https:\/\/bersub.com\/en\/#website","url":"https:\/\/bersub.com\/en\/","name":"Bersub","description":"","publisher":{"@id":"https:\/\/bersub.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bersub.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/bersub.com\/en\/#organization","name":"Bersub","url":"https:\/\/bersub.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/bersub.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/bersub.com\/wp-content\/uploads\/2021\/01\/logo-bersub-blanc.png","contentUrl":"https:\/\/bersub.com\/wp-content\/uploads\/2021\/01\/logo-bersub-blanc.png","width":400,"height":144,"caption":"Bersub"},"image":{"@id":"https:\/\/bersub.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/bersub.com\/es\/wp-json\/wp\/v2\/product\/9698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bersub.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bersub.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/bersub.com\/es\/wp-json\/wp\/v2\/product\/9698\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bersub.com\/es\/wp-json\/wp\/v2\/media\/5590"}],"wp:attachment":[{"href":"https:\/\/bersub.com\/es\/wp-json\/wp\/v2\/media?parent=9698"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bersub.com\/es\/wp-json\/wp\/v2\/product_brand?post=9698"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bersub.com\/es\/wp-json\/wp\/v2\/product_cat?post=9698"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bersub.com\/es\/wp-json\/wp\/v2\/product_tag?post=9698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}